{"id":526,"count":1,"description":"","link":"https:\/\/tollscout.eu\/cs\/tag\/zpusob-platby-cs\/","name":"Zp\u016fsob platby","slug":"zpusob-platby-cs","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zp\u016fsob platby Archive - Tollscout\u00ae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tollscout.eu\/cs\/tag\/zpusob-platby-cs\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zp\u016fsob platby Archive - Tollscout\u00ae\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tollscout.eu\/cs\/tag\/zpusob-platby-cs\/\" \/>\n<meta property=\"og:site_name\" content=\"Tollscout\u00ae\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tollscout.eu\/wp-content\/uploads\/2023\/08\/logo_color_360x92px.png\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"92\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@tollscout\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/tollscout.eu\\\/cs\\\/tag\\\/zpusob-platby-cs\\\/\",\"url\":\"https:\\\/\\\/tollscout.eu\\\/cs\\\/tag\\\/zpusob-platby-cs\\\/\",\"name\":\"Zp\u016fsob platby Archive - Tollscout\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tollscout.eu\\\/cs\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tollscout.eu\\\/cs\\\/tag\\\/zpusob-platby-cs\\\/#breadcrumb\"},\"inLanguage\":\"cs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tollscout.eu\\\/cs\\\/tag\\\/zpusob-platby-cs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/tollscout.eu\\\/cs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zp\u016fsob platby\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tollscout.eu\\\/cs\\\/#website\",\"url\":\"https:\\\/\\\/tollscout.eu\\\/cs\\\/\",\"name\":\"Tollscout\u00ae\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/tollscout.eu\\\/cs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tollscout.eu\\\/cs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tollscout.eu\\\/cs\\\/#organization\",\"name\":\"TollScout\",\"alternateName\":\"TollScout\",\"url\":\"https:\\\/\\\/tollscout.eu\\\/cs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/tollscout.eu\\\/cs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tollscout.eu\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo_social_media_1024.png\",\"contentUrl\":\"https:\\\/\\\/tollscout.eu\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo_social_media_1024.png\",\"width\":1024,\"height\":1024,\"caption\":\"TollScout\"},\"image\":{\"@id\":\"https:\\\/\\\/tollscout.eu\\\/cs\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/tollscout\",\"https:\\\/\\\/x.com\\\/tollscout\",\"https:\\\/\\\/instagram.com\\\/tollscout\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zp\u016fsob platby Archive - Tollscout\u00ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tollscout.eu\/cs\/tag\/zpusob-platby-cs\/","og_locale":"cs_CZ","og_type":"article","og_title":"Zp\u016fsob platby Archive - Tollscout\u00ae","og_url":"https:\/\/tollscout.eu\/cs\/tag\/zpusob-platby-cs\/","og_site_name":"Tollscout\u00ae","og_image":[{"width":360,"height":92,"url":"https:\/\/tollscout.eu\/wp-content\/uploads\/2023\/08\/logo_color_360x92px.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@tollscout","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/tollscout.eu\/cs\/tag\/zpusob-platby-cs\/","url":"https:\/\/tollscout.eu\/cs\/tag\/zpusob-platby-cs\/","name":"Zp\u016fsob platby Archive - Tollscout\u00ae","isPartOf":{"@id":"https:\/\/tollscout.eu\/cs\/#website"},"breadcrumb":{"@id":"https:\/\/tollscout.eu\/cs\/tag\/zpusob-platby-cs\/#breadcrumb"},"inLanguage":"cs"},{"@type":"BreadcrumbList","@id":"https:\/\/tollscout.eu\/cs\/tag\/zpusob-platby-cs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/tollscout.eu\/cs\/"},{"@type":"ListItem","position":2,"name":"Zp\u016fsob platby"}]},{"@type":"WebSite","@id":"https:\/\/tollscout.eu\/cs\/#website","url":"https:\/\/tollscout.eu\/cs\/","name":"Tollscout\u00ae","description":"","publisher":{"@id":"https:\/\/tollscout.eu\/cs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tollscout.eu\/cs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/tollscout.eu\/cs\/#organization","name":"TollScout","alternateName":"TollScout","url":"https:\/\/tollscout.eu\/cs\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/tollscout.eu\/cs\/#\/schema\/logo\/image\/","url":"https:\/\/tollscout.eu\/wp-content\/uploads\/2023\/11\/logo_social_media_1024.png","contentUrl":"https:\/\/tollscout.eu\/wp-content\/uploads\/2023\/11\/logo_social_media_1024.png","width":1024,"height":1024,"caption":"TollScout"},"image":{"@id":"https:\/\/tollscout.eu\/cs\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/tollscout","https:\/\/x.com\/tollscout","https:\/\/instagram.com\/tollscout"]}]}},"_links":{"self":[{"href":"https:\/\/tollscout.eu\/cs\/wp-json\/wp\/v2\/tags\/526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tollscout.eu\/cs\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tollscout.eu\/cs\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tollscout.eu\/cs\/wp-json\/wp\/v2\/posts?tags=526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}